{"id":8511,"date":"2021-08-19T16:00:43","date_gmt":"2021-08-19T14:00:43","guid":{"rendered":"https:\/\/www.appetizerblog.com\/?p=8511"},"modified":"2024-06-21T15:39:13","modified_gmt":"2024-06-21T13:39:13","slug":"infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida","status":"publish","type":"post","link":"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/","title":{"rendered":"[INFOGR\u00c1FICO] Perros versus Gatos: desde los sentidos al comportamiento de alimentaci\u00f3n, anatom\u00eda de una comida"},"content":{"rendered":"<h1><\/h1>\n<p><span style=\"font-size: 12pt;\"><div class=\"intro\">La alimentaci\u00f3n es una cascada sensorial din\u00e1mica en la que ocurren m\u00faltiples interacciones entre un alimento y el animal. Con diferentes sistemas sensoriales y anatom\u00edas, los gatos y perros no se comportan de igual modo con respecto a los alimentos<\/span>.<span style=\"font-size: 12pt;\"><\/div><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Como los humanos, los gatos y perros tienen sus propios comportamientos de alimentaci\u00f3n. Observando detalladamente, es f\u00e1cil notar que su forma de comer no es la misma. Y la diferencia comienza desde la selecci\u00f3n de alimentos.<\/p>\n<p>&nbsp;<\/p>\n<h1><a href=\"https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2021\/08\/DPF_BLOG_CAT_AND_DOG-MEALS_INFOGRAPHY-VF-06_2021_SP_v3.pdf\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-8531 size-full\" src=\"https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2021\/08\/DPF_BLOG_CAT_AND_DOG-MEALS_INFOGRAPHY-VF-06_2021_SP_v3-scaled.jpg\" alt=\"\" width=\"909\" height=\"2560\" srcset=\"https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2021\/08\/DPF_BLOG_CAT_AND_DOG-MEALS_INFOGRAPHY-VF-06_2021_SP_v3-scaled.jpg 909w, https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2021\/08\/DPF_BLOG_CAT_AND_DOG-MEALS_INFOGRAPHY-VF-06_2021_SP_v3-106x300.jpg 106w, https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2021\/08\/DPF_BLOG_CAT_AND_DOG-MEALS_INFOGRAPHY-VF-06_2021_SP_v3-768x2164.jpg 768w, https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2021\/08\/DPF_BLOG_CAT_AND_DOG-MEALS_INFOGRAPHY-VF-06_2021_SP_v3-545x1536.jpg 545w, https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2021\/08\/DPF_BLOG_CAT_AND_DOG-MEALS_INFOGRAPHY-VF-06_2021_SP_v3-727x2048.jpg 727w, https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2021\/08\/DPF_BLOG_CAT_AND_DOG-MEALS_INFOGRAPHY-VF-06_2021_SP_v3-710x2000.jpg 710w, https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2021\/08\/DPF_BLOG_CAT_AND_DOG-MEALS_INFOGRAPHY-VF-06_2021_SP_v3-350x986.jpg 350w\" sizes=\"(max-width: 909px) 100vw, 909px\" \/><\/a><\/h1>\n<h1><\/h1>\n<p>&nbsp;<\/p>\n<h2>Desde la selecci\u00f3n de alimentos a la masticaci\u00f3n, un gato no es un perro<\/h2>\n<p>&nbsp;<\/p>\n<p>Mientras que los perros huelen, eligen y comen su alimento r\u00e1pidamente, generalmente qued\u00e1ndose con su primera elecci\u00f3n, los gatos tienden a dudar, tomarse su tiempo antes de comer, y cambiar de idea varias veces al encontrarse con varios alimentos.<\/p>\n<p>&nbsp;<\/p>\n<p>Las formas de agarrar y masticar tambi\u00e9n difieren entre los gatos y los perros, especialmente en el caso del alimento seco para mascotas.<\/p>\n<p>&nbsp;<\/p>\n<p>Habitualmente, los perros agarran las croquetas con sus dientes y las trituran o las tragan directamente.<br \/>\nLos gatos agarran las croquetas con sus lenguas, dientes o labios. Las tragan directamente o las enrollan con su lengua hacia sus molares, para romperlas en peque\u00f1as partes.<\/p>\n<p>&nbsp;<\/p>\n<p>Para entender estas diferencias en el comportamiento, debes indagar en los campos de la anatom\u00eda y los sentidos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>Comportamiento de alimentaci\u00f3n de los gatos y los perros: una historia de sentidos<\/h2>\n<p>&nbsp;<\/p>\n<p>El comportamiento de alimentaci\u00f3n mayormente resulta de la interacci\u00f3n entre las propiedades organol\u00e9pticas de los alimentos y los sistemas sensoriales de las mascotas.<\/p>\n<p>&nbsp;<\/p>\n<p>Olor, color, textura, forma, sabor\u2026 en cada paso de la comida, los diferentes atributos de los alimentos estimulan los distintos \u00f3rganos y sentidos de las mascotas.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Y aqu\u00ed se encuentra la variaci\u00f3n! Desde la cantidad de papilas gustativas hasta la cantidad de dientes, los gatos y los perros no son iguales. Las diferencias en su agudeza sensorial y anatom\u00eda hacen que se comporten de forma diferente frente a los alimentos.<\/p>\n<p>&nbsp;<\/p>\n<p>Los perros tienen, por ejemplo, un gran sentido del olfato dado que un diez por ciento de su cerebro est\u00e1 dedicado a este sentido. Por eso no es sorprendente que huelan mucho y conf\u00eden en sus narices para elegir los alimentos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Una de las diferencias entre los gatos y los perros es que sus mand\u00edbulas est\u00e1n limitadas a realizar movimientos verticales. Probablemente por esa raz\u00f3n no muelen las croquetas, sino que las cortan y rompen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>Un primer paso hacia la palatabilidad<\/h2>\n<p>&nbsp;<\/p>\n<p>Conocer sobre la fisiolog\u00eda y entender el comportamiento alimenticio es un primer paso para ajustar los alimentos a las necesidades espec\u00edficas de los gatos y de los perros.<\/p>\n<p>&nbsp;<\/p>\n<p>El siguiente paso l\u00f3gico para satisfacer sus apetitos es conocer sus preferencias y asegurarse que los alimentos posean todos los atributos que generar\u00e1n palatabilidad.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Pero esa es otra historia! Continuar\u00e1&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubra por qu\u00e9 los gatos y los perros no comen de la misma manera<\/p>\n","protected":false},"author":9,"featured_media":6070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[345],"tags":[625,624,425,426,626],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[INFOGR\u00c1FICO] Perros versus Gatos: desde los sentidos al comportamiento de alimentaci\u00f3n, anatom\u00eda de una comida - Appetizer - Symrise Pet Food<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[INFOGR\u00c1FICO] Perros versus Gatos: desde los sentidos al comportamiento de alimentaci\u00f3n, anatom\u00eda de una comida - Appetizer - Symrise Pet Food\" \/>\n<meta property=\"og:description\" content=\"Descubra por qu\u00e9 los gatos y los perros no comen de la misma manera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/\" \/>\n<meta property=\"og:site_name\" content=\"Appetizer - Symrise Pet Food\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-19T14:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T13:39:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2019\/04\/DPF_BLOG_CAT_AND_DOG_HEADER_1920X720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"3 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#organization\",\"name\":\"Symrise Pet Food\",\"url\":\"https:\/\/www.appetizerblog.com\/es\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2018\/10\/DPF-APPETIZER-IDENTITY-292x42-2-1-e1539605039289.png\",\"width\":280,\"height\":60,\"caption\":\"Symrise Pet Food\"},\"image\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#website\",\"url\":\"https:\/\/www.appetizerblog.com\/es\/\",\"name\":\"Appetizer - Symrise Pet Food\",\"description\":\"Feeding the curiosity of pet food professionals\",\"publisher\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.appetizerblog.com\/es\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.appetizerblog.com\/wp-content\/uploads\/2019\/04\/DPF_BLOG_CAT_AND_DOG_HEADER_1920X720.jpg\",\"width\":1920,\"height\":720},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#webpage\",\"url\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/\",\"name\":\"[INFOGR\\u00c1FICO] Perros versus Gatos: desde los sentidos al comportamiento de alimentaci\\u00f3n, anatom\\u00eda de una comida - Appetizer - Symrise Pet Food\",\"isPartOf\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#primaryimage\"},\"datePublished\":\"2021-08-19T14:00:43+00:00\",\"dateModified\":\"2024-06-21T13:39:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/\",\"url\":\"https:\/\/www.appetizerblog.com\/es\/\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/topics\/palatabilidad\/\",\"url\":\"https:\/\/www.appetizerblog.com\/es\/topics\/palatabilidad\/\",\"name\":\"Palatabilidad\"}},{\"@type\":\"ListItem\",\"position\":3,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/\",\"url\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/\",\"name\":\"[INFOGR\\u00c1FICO] Perros versus Gatos: desde los sentidos al comportamiento de alimentaci\\u00f3n, anatom\\u00eda de una comida\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#\/schema\/person\/8354d3cea88c82e9da74249be03f102c\"},\"headline\":\"[INFOGR\\u00c1FICO] Perros versus Gatos: desde los sentidos al comportamiento de alimentaci\\u00f3n, anatom\\u00eda de una comida\",\"datePublished\":\"2021-08-19T14:00:43+00:00\",\"dateModified\":\"2024-06-21T13:39:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#primaryimage\"},\"keywords\":\"Comida,Comportamiento de alimentici\\u00f3n,gato,perro,Sentidos\",\"articleSection\":\"Palatabilidad\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.appetizerblog.com\/es\/infografico-perros-versus-gatos-desde-los-sentidos-al-comportamiento-de-alimentacion-anatomia-de-una-comida\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#\/schema\/person\/8354d3cea88c82e9da74249be03f102c\",\"name\":\"Diego Monteleone\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.appetizerblog.com\/es\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f82ed49d3667aaeee4ae030b1d1c4117?s=96&d=mm&r=g\",\"caption\":\"Diego Monteleone\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/posts\/8511"}],"collection":[{"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/comments?post=8511"}],"version-history":[{"count":8,"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/posts\/8511\/revisions"}],"predecessor-version":[{"id":10609,"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/posts\/8511\/revisions\/10609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/media\/6070"}],"wp:attachment":[{"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/media?parent=8511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/categories?post=8511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.appetizerblog.com\/es\/wp-json\/wp\/v2\/tags?post=8511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}